{"id":373,"date":"2026-07-09T16:24:11","date_gmt":"2026-07-09T14:24:11","guid":{"rendered":"https:\/\/lanascodex.com\/?page_id=373"},"modified":"2026-07-27T10:21:27","modified_gmt":"2026-07-27T08:21:27","slug":"le-secret-de-la-riviere-bleu-tome-3","status":"publish","type":"page","link":"https:\/\/lanascodex.com\/en\/le-secret-de-la-riviere-bleu-tome-3\/","title":{"rendered":"The Secret of the Blue River \u2013 Volume 3"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"373\" class=\"elementor elementor-373\">\n\t\t\t\t<div class=\"elementor-element elementor-element-32a3132 e-flex e-con-boxed e-con e-parent\" data-id=\"32a3132\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6d094b6 elementor-widget elementor-widget-heading\" data-id=\"6d094b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">LE SECRET DE LA RIVIERE BLEU<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cb4ee0b elementor-widget elementor-widget-text-editor\" data-id=\"cb4ee0b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>TOME 3 &#8211; SERIE LES PLAINES<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-32bc16c e-con e-atomic-element e-flexbox-base e-c6e15e1\" data-id=\"32bc16c\" data-element_type=\"e-flexbox\" data-e-type=\"e-flexbox\" data-interaction-id=\"32bc16c\">\n    <div class=\"elementor-element elementor-element-b39d9f0 e-flex e-con-boxed e-con e-parent\" data-id=\"b39d9f0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<h2 data-interaction-id=\"16141ed\" class=\"e-16141ed-4599f32 e-heading-base\">\ud83d\udecd\ufe0f Commander ce Livre<\/h2>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\n<\/div>\n<div class=\"elementor-element elementor-element-2ae2726 e-con e-atomic-element e-flexbox-base e-8e8ff0f\" data-id=\"2ae2726\" data-element_type=\"e-flexbox\" data-e-type=\"e-flexbox\" data-interaction-id=\"2ae2726\">\n    <div class=\"elementor-element elementor-element-8bd843c e-con e-atomic-element e-flexbox-base e-c37fa76\" data-id=\"8bd843c\" data-element_type=\"e-flexbox\" data-e-type=\"e-flexbox\" data-interaction-id=\"8bd843c\">\n    \t\t<div class=\"elementor-element elementor-element-c7a7a32 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"c7a7a32\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.amazon.fr\/dp\/B0GZ47PRLX\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Version Fran\u00e7aise papier sur Amazon<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c83b7cc elementor-align-center elementor-widget elementor-widget-button\" data-id=\"c83b7cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/lanascodex.gumroad.com\/l\/tdszoe\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">T\u00e9l\u00e9charger la version PDF \/ Num\u00e9rique<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\n<\/div>\n<div class=\"elementor-element elementor-element-d4ece05 e-con e-atomic-element e-flexbox-base e-c209589\" data-id=\"d4ece05\" data-element_type=\"e-flexbox\" data-e-type=\"e-flexbox\" data-interaction-id=\"d4ece05\">\n    \t\t<div class=\"elementor-element elementor-element-10fb12a elementor-align-center elementor-widget elementor-widget-button\" data-id=\"10fb12a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.amazon.fr\/dp\/B0GZ71ND1Z\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\ud83c\uddeb\ud83c\uddf7\ud83c\uddec\ud83c\udde7 Version Bilingue papier sur Amazon<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aa1c0fb elementor-align-center elementor-widget elementor-widget-button\" data-id=\"aa1c0fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/lanascodex.gumroad.com\/l\/quxse\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">T\u00e9l\u00e9charger la version PDF \/ Num\u00e9rique<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\n<\/div>\n<div class=\"elementor-element elementor-element-c38e2b2 e-con e-atomic-element e-flexbox-base e-3e2341a\" data-id=\"c38e2b2\" data-element_type=\"e-flexbox\" data-e-type=\"e-flexbox\" data-interaction-id=\"c38e2b2\">\n    \t\t<div class=\"elementor-element elementor-element-ccf0d3b elementor-align-center elementor-widget elementor-widget-button\" data-id=\"ccf0d3b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.amazon.com\/dp\/B0GZ87322Q\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\ud83c\uddec\ud83c\udde7\ud83c\uddfa\ud83c\uddf8 Version Anglaise (Full English) sur Amazon<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b0a8c3 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"7b0a8c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/lanascodex.gumroad.com\/l\/taorip\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">T\u00e9l\u00e9charger la version PDF \/ Num\u00e9rique<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\n<\/div>\n\n<\/div>\n<div class=\"elementor-element elementor-element-228179d e-con e-atomic-element e-flexbox-base e-03f085a\" data-id=\"228179d\" data-element_type=\"e-flexbox\" data-e-type=\"e-flexbox\" data-interaction-id=\"228179d\">\n    \t\t\t<h2 data-interaction-id=\"3ceb564\" class=\"e-heading-base\">Une aventure aquatique et myst\u00e9rieuse pour notre trio d'explorateurs !<\/h2>\n\t\t\n<\/div>\n<div class=\"elementor-element elementor-element-1a78419 e-con e-atomic-element e-flexbox-base e-88a02df\" data-id=\"1a78419\" data-element_type=\"e-flexbox\" data-e-type=\"e-flexbox\" data-interaction-id=\"1a78419\">\n    <div class=\"elementor-element elementor-element-fa7547b e-con e-atomic-element e-flexbox-base e-70ca82c\" data-id=\"fa7547b\" data-element_type=\"e-flexbox\" data-e-type=\"e-flexbox\" data-interaction-id=\"fa7547b\">\n    \t\t\t<p class=\"e-paragraph-base\" data-interaction-id=\"66d1c7d\"><strong>Le premier pas vers une lecture accompagn\u00e9e et joyeuse pour les 3-7 ans !<\/strong><br><br>Offrez \u00e0 votre enfant bien plus qu\u2019une simple histoire : une aventure magique et interactive qui l'accompagnera de la maternelle au CP.<br><br>\ud83c\udfa8 <strong>Style d'illustrations :<\/strong> Un univers 3D moderne, doux et chaleureux qui captive instantan\u00e9ment l'attention des petits comme des grands.<br><br>\ud83d\udcd6 R\u00e9sum\u00e9 de l'AventureLes Trois Malins (Malo, Mia et Mochi) d\u00e9couvrent que la rivi\u00e8re du village est obstru\u00e9e par un amas de d\u00e9bris, ce qui rend  Grenouille et les poissons malheureux.<br><br>Gr\u00e2ce \u00e0 leur esprit d'\u00e9quipe et leur courage, ils nettoient le courant et lib\u00e8rent l'acc\u00e8s \u00e0 une grotte secr\u00e8te dissimul\u00e9e derri\u00e8re le barrage.<br><br>\u00c0 l'int\u00e9rieur de la grotte, guid\u00e9s par des cristaux lumineux, ils utilisent une cl\u00e9 en bois pour d\u00e9placer un rocher. Ils y d\u00e9couvrent le troisi\u00e8me secret de leur qu\u00eate : un vieux m\u00e9daillon en \u00e9tain grav\u00e9 d'une \u00e9toile...<br><br>\u2728 Les + de ce Livre<br><br><strong>\ud83e\udde9 Jeu Interactif :<\/strong> Un \"Cherche et Trouve\" int\u00e9gr\u00e9 ! Le petit escargot coquin se cache \u00e0 chaque page pour stimuler le sens de l'observation de votre enfant.<br><br><strong>\ud83c\udfb6 Lecture Rythm\u00e9e :<\/strong> Une histoire enti\u00e8rement \u00e9crite avec des rimes douces et simples, accompagn\u00e9e d'un po\u00e8me in\u00e9dit \u00e0 la fin du livre.<br><br><strong>\ud83c\udf31 Valeurs Fortes :<\/strong> Une aventure qui se termine par une note \u00e9cologique, rappelant l'importance de prot\u00e9ger l'eau et de ramasser les d\u00e9chets pour pr\u00e9server la beaut\u00e9 de la nature.<br><br><strong>\ud83d\udcad Moment d'\u00c9change :<\/strong> Une question de r\u00e9flexion et une morale \u00e0 la fin pour discuter de l'\u00e9cologie et de l'histoire ensemble.<\/p>\n\t\t\n<\/div>\n<div class=\"elementor-element elementor-element-9b4bec2 e-con e-atomic-element e-flexbox-base e-93178f0\" data-id=\"9b4bec2\" data-element_type=\"e-flexbox\" data-e-type=\"e-flexbox\" data-interaction-id=\"9b4bec2\">\n    \t\t\t<img fetchpriority=\"high\" decoding=\"async\" class=\"e-image-base\" data-interaction-id=\"77bd57a\" id=\"345\" src=\"https:\/\/i0.wp.com\/lanascodex.com\/wp-content\/uploads\/2026\/07\/Gemini_Generated_Image_ol5iugol5iugol5i.png?fit=2048%2C2080&amp;#038;ssl=1\" width=\"2048\" height=\"2080\" srcset=\"https:\/\/i0.wp.com\/lanascodex.com\/wp-content\/uploads\/2026\/07\/Gemini_Generated_Image_ol5iugol5iugol5i.png?w=2048&amp;ssl=1 2048w, https:\/\/i0.wp.com\/lanascodex.com\/wp-content\/uploads\/2026\/07\/Gemini_Generated_Image_ol5iugol5iugol5i.png?resize=295%2C300&amp;ssl=1 295w, https:\/\/i0.wp.com\/lanascodex.com\/wp-content\/uploads\/2026\/07\/Gemini_Generated_Image_ol5iugol5iugol5i.png?resize=1008%2C1024&amp;ssl=1 1008w, https:\/\/i0.wp.com\/lanascodex.com\/wp-content\/uploads\/2026\/07\/Gemini_Generated_Image_ol5iugol5iugol5i.png?resize=768%2C780&amp;ssl=1 768w, https:\/\/i0.wp.com\/lanascodex.com\/wp-content\/uploads\/2026\/07\/Gemini_Generated_Image_ol5iugol5iugol5i.png?resize=1512%2C1536&amp;ssl=1 1512w, https:\/\/i0.wp.com\/lanascodex.com\/wp-content\/uploads\/2026\/07\/Gemini_Generated_Image_ol5iugol5iugol5i.png?resize=2016%2C2048&amp;ssl=1 2016w\" alt=\"\"\/>\t\t\n<\/div>\n\n<\/div>\n<div class=\"elementor-element elementor-element-c15f61f e-con e-atomic-element e-flexbox-base e-209f13d\" data-id=\"c15f61f\" data-element_type=\"e-flexbox\" data-e-type=\"e-flexbox\" data-interaction-id=\"c15f61f\">\n    <div class=\"elementor-element elementor-element-373c222 e-flex e-con-boxed e-con e-parent\" data-id=\"373c222\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b422166 elementor-widget elementor-widget-image\" data-id=\"b422166\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"559\" src=\"https:\/\/i0.wp.com\/lanascodex.com\/wp-content\/uploads\/2026\/07\/Gemini_Generated_Image_8jxa1w8jxa1w8jxa.png?fit=1024%2C559&amp;ssl=1\" class=\"attachment-large size-large wp-image-480\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/lanascodex.com\/wp-content\/uploads\/2026\/07\/Gemini_Generated_Image_8jxa1w8jxa1w8jxa.png?w=1408&amp;ssl=1 1408w, https:\/\/i0.wp.com\/lanascodex.com\/wp-content\/uploads\/2026\/07\/Gemini_Generated_Image_8jxa1w8jxa1w8jxa.png?resize=300%2C164&amp;ssl=1 300w, https:\/\/i0.wp.com\/lanascodex.com\/wp-content\/uploads\/2026\/07\/Gemini_Generated_Image_8jxa1w8jxa1w8jxa.png?resize=1024%2C559&amp;ssl=1 1024w, https:\/\/i0.wp.com\/lanascodex.com\/wp-content\/uploads\/2026\/07\/Gemini_Generated_Image_8jxa1w8jxa1w8jxa.png?resize=768%2C419&amp;ssl=1 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" data-attachment-id=\"480\" data-permalink=\"https:\/\/lanascodex.com\/en\/le-secret-de-la-riviere-bleu-tome-3\/gemini_generated_image_8jxa1w8jxa1w8jxa\/\" data-orig-file=\"https:\/\/i0.wp.com\/lanascodex.com\/wp-content\/uploads\/2026\/07\/Gemini_Generated_Image_8jxa1w8jxa1w8jxa.png?fit=1408%2C768&amp;ssl=1\" data-orig-size=\"1408,768\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;,&quot;alt&quot;:&quot;&quot;}\" data-image-title=\"Gemini_Generated_Image_8jxa1w8jxa1w8jxa\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/lanascodex.com\/wp-content\/uploads\/2026\/07\/Gemini_Generated_Image_8jxa1w8jxa1w8jxa.png?fit=1024%2C559&amp;ssl=1\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\n<\/div>\n<div class=\"elementor-element elementor-element-500e39c e-con e-atomic-element e-flexbox-base e-76984ee\" data-id=\"500e39c\" data-element_type=\"e-flexbox\" data-e-type=\"e-flexbox\" data-interaction-id=\"500e39c\">\n    \t\t\t<h2 data-interaction-id=\"5a3dd5c\" class=\"e-5a3dd5c-be7bcf0 e-heading-base\">BIENTOT LA VIDEO DU LIVRE<\/h2>\n\t\t\n<\/div>\n\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>LE SECRET DE LA RIVIERE BLEU TOME 3 &#8211; SERIE LES PLAINES \ud83d\udecd\ufe0f Commander ce Livre Version Fran\u00e7aise papier sur [&hellip;]<\/p>\n","protected":false},"author":281509952,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"","ast-site-content-layout":"full-width-container","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_wpcom_ai_launchpad_about_page":false,"_wpcom_ai_launchpad_gallery_page":false,"_wpcom_ai_launchpad_contact_page":false,"_wpcom_ai_launchpad_events_page":false,"_wpcom_ai_launchpad_video_page":false,"_wpcom_ai_launchpad_portfolio_piece":false,"footnotes":""},"class_list":["post-373","page","type-page","status-publish","hentry"],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/PhkbuZ-61","jetpack-related-posts":[{"id":358,"url":"https:\/\/lanascodex.com\/en\/le-moulin-aux-ailes-cassees-tome-2\/","url_meta":{"origin":373,"position":0},"title":"The Mill with Broken Wings - Volume 2","author":"clairefinaud","date":"July 9, 2026","format":false,"excerpt":"LE MOULIN AUX AILES CASSEES TOME 2 -\u00a0 SERIE LES PLAINES \ud83d\udecd\ufe0f Commander ce Livre Version Fran\u00e7aise papier sur Amazon T\u00e9l\u00e9charger la version PDF \/ Num\u00e9rique Version Bilingue sur Amazon T\u00e9l\u00e9charger la version PDF \/ Num\u00e9rique \ud83c\uddec\ud83c\udde7\ud83c\uddfa\ud83c\uddf8 Version ENGLISH sur Amazon T\u00e9l\u00e9charger la version PDF \/ Num\u00e9rique \ud83e\udd56 Tome 2\u2026","rel":"","context":"Similar post","block_context":{"text":"Similar post","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lanascodex.com\/wp-content\/uploads\/2026\/07\/FRANCAIS-Moulin-aux-Ailes-Cassees-1-1.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lanascodex.com\/wp-content\/uploads\/2026\/07\/FRANCAIS-Moulin-aux-Ailes-Cassees-1-1.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lanascodex.com\/wp-content\/uploads\/2026\/07\/FRANCAIS-Moulin-aux-Ailes-Cassees-1-1.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lanascodex.com\/wp-content\/uploads\/2026\/07\/FRANCAIS-Moulin-aux-Ailes-Cassees-1-1.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/lanascodex.com\/wp-content\/uploads\/2026\/07\/FRANCAIS-Moulin-aux-Ailes-Cassees-1-1.png?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/lanascodex.com\/wp-content\/uploads\/2026\/07\/FRANCAIS-Moulin-aux-Ailes-Cassees-1-1.png?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":352,"url":"https:\/\/lanascodex.com\/en\/le-mystere-du-grand-potager-tome-1\/","url_meta":{"origin":373,"position":1},"title":"THE MYSTERY OF THE GREAT VEGETABLE GARDEN \u2013 VOLUME 1","author":"clairefinaud","date":"July 9, 2026","format":false,"excerpt":"LE MYSTERE DU GRAND POTAGER LES PLAINES Une enqu\u00eate palpitante au c\u0153ur du village des champignons ! Commander ce LivreL'aventure du Tome 1 s'adapte au rythme de votre enfant ! Choisissez la langue et le format id\u00e9al pour votre petit explorateur : \ud83c\uddeb\ud83c\uddf7 Version Fran\u00e7aise AMAZON T\u00e9l\u00e9charger la version PDF\u2026","rel":"","context":"Similar post","block_context":{"text":"Similar post","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lanascodex.com\/wp-content\/uploads\/2026\/07\/Gemini_Generated_Image_ye0enpye0enpye0e.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lanascodex.com\/wp-content\/uploads\/2026\/07\/Gemini_Generated_Image_ye0enpye0enpye0e.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lanascodex.com\/wp-content\/uploads\/2026\/07\/Gemini_Generated_Image_ye0enpye0enpye0e.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lanascodex.com\/wp-content\/uploads\/2026\/07\/Gemini_Generated_Image_ye0enpye0enpye0e.png?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":163,"url":"https:\/\/lanascodex.com\/en\/collection-lapins\/","url_meta":{"origin":373,"position":2},"title":"RABBIT COLLECTION","author":"clairefinaud","date":"July 9, 2026","format":false,"excerpt":"La Communaut\u00e9 des Lapins Des albums jeunesse inclusifs, ludiques et interactifs pour redonner le plaisir de lire \u00e0 tous les enfants Commander sur Amazon A d\u00e9couvrir Commander sur Amazon A d\u00e9couvrir Commander sur Amazon A d\u00e9couvrir J'ai cr\u00e9\u00e9 La Communaut\u00e9 des Lapins avec une mission simple : offrir \u00e0 chaque\u2026","rel":"","context":"Similar post","block_context":{"text":"Similar post","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lanascodex.com\/wp-content\/uploads\/2026\/07\/Gemini_Generated_Image_ye0enpye0enpye0e.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lanascodex.com\/wp-content\/uploads\/2026\/07\/Gemini_Generated_Image_ye0enpye0enpye0e.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lanascodex.com\/wp-content\/uploads\/2026\/07\/Gemini_Generated_Image_ye0enpye0enpye0e.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lanascodex.com\/wp-content\/uploads\/2026\/07\/Gemini_Generated_Image_ye0enpye0enpye0e.png?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":137,"url":"https:\/\/lanascodex.com\/en\/","url_meta":{"origin":373,"position":3},"title":"HOME","author":"clairefinaud","date":"July 7, 2026","format":false,"excerpt":"LANA'S CODEX ACTUALITES \u00c0 la Une dans les Monts du Lyonnais ! D\u00e9couvrez l'article du magazine Vivre \u00e0 Gr\u00e9zieu consacr\u00e9 \u00e0 Lana\u2019s Codex, une initiative locale et ind\u00e9pendante en faveur de la litt\u00e9rature jeunesse et de l'inclusion. LA COMMUNAUTE DES LAPINS LES 3 MALINS Commander sur Amazon A DECOUVRIR Commander\u2026","rel":"","context":"Similar post","block_context":{"text":"Similar post","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lanascodex.com\/wp-content\/uploads\/2026\/07\/A-la-Une-dans-les-Monts-du-Lyonnais-.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lanascodex.com\/wp-content\/uploads\/2026\/07\/A-la-Une-dans-les-Monts-du-Lyonnais-.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lanascodex.com\/wp-content\/uploads\/2026\/07\/A-la-Une-dans-les-Monts-du-Lyonnais-.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lanascodex.com\/wp-content\/uploads\/2026\/07\/A-la-Une-dans-les-Monts-du-Lyonnais-.png?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":173,"url":"https:\/\/lanascodex.com\/en\/collection-bilingue\/","url_meta":{"origin":373,"position":4},"title":"Bilingual Collection","author":"clairefinaud","date":"July 9, 2026","format":false,"excerpt":"COLLECTION BILINGUE Apprendre et grandir en s'amusant dans deux langues ! Ma Collection de Livres Bilingues Bienvenue dans l'espace bilingue de la Communaut\u00e9 des Lapins !Parce que l'ouverture au monde commence d\u00e8s le plus jeune \u00e2ge, j'ai con\u00e7u cette collection unique d'albums et de cahiers d'activit\u00e9s bilingues.Id\u00e9als pour les enfants\u2026","rel":"","context":"Similar post","block_context":{"text":"Similar post","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lanascodex.com\/wp-content\/uploads\/2026\/07\/Design-sans-titre-11.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":606,"url":"https:\/\/lanascodex.com\/en\/le-secret-de-la-baguette-etoilee\/","url_meta":{"origin":373,"position":5},"title":"LE SECRET DE LA BAGUETTE ETOILEE","author":"clairefinaud","date":"July 27, 2026","format":false,"excerpt":"LE SECRET DE LA BAGUETTE ETOILEE COMMANDER SUR AMAZON Tim\u00e9o et \u00c9clair : L'Aventure Magique M\u00eame sous la grisaille, Tim\u00e9o, notre super petit magicien en herbe, et \u00c9clair, son chien fid\u00e8le, sont pr\u00eats pour le grand moment : ils montent sur sc\u00e8ne pour leur spectacle de magie!Ce livre, c'est bien\u2026","rel":"","context":"Similar post","block_context":{"text":"Similar post","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/lanascodex.com\/wp-content\/uploads\/2026\/07\/couverture-dys.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/lanascodex.com\/wp-content\/uploads\/2026\/07\/couverture-dys.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/lanascodex.com\/wp-content\/uploads\/2026\/07\/couverture-dys.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/lanascodex.com\/wp-content\/uploads\/2026\/07\/couverture-dys.png?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/lanascodex.com\/wp-content\/uploads\/2026\/07\/couverture-dys.png?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/lanascodex.com\/en\/wp-json\/wp\/v2\/pages\/373","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lanascodex.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lanascodex.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lanascodex.com\/en\/wp-json\/wp\/v2\/users\/281509952"}],"replies":[{"embeddable":true,"href":"https:\/\/lanascodex.com\/en\/wp-json\/wp\/v2\/comments?post=373"}],"version-history":[{"count":14,"href":"https:\/\/lanascodex.com\/en\/wp-json\/wp\/v2\/pages\/373\/revisions"}],"predecessor-version":[{"id":587,"href":"https:\/\/lanascodex.com\/en\/wp-json\/wp\/v2\/pages\/373\/revisions\/587"}],"wp:attachment":[{"href":"https:\/\/lanascodex.com\/en\/wp-json\/wp\/v2\/media?parent=373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}